{"id":111,"date":"2020-07-16T10:48:27","date_gmt":"2020-07-16T08:48:27","guid":{"rendered":"https:\/\/www.culturalvila-seca.cat\/caramelles\/?post_type=noticia&#038;p=111"},"modified":"2020-09-24T06:42:57","modified_gmt":"2020-09-24T04:42:57","slug":"al-setembre-reprenem-els-assajos","status":"publish","type":"noticia","link":"https:\/\/www.culturalvila-seca.cat\/caramelles\/actualitat\/al-setembre-reprenem-els-assajos\/","title":{"rendered":"Al setembre reprenem els assajos"},"content":{"rendered":"\n<p>Despr\u00e9s de l&#8217;estiu, comen\u00e7arem novament els assajos, tan aviat com sapiguem quin dia tenim una sala reservada al conservatori, us farem saber el dia de la setmana i l&#8217;hora que ens trobarem per cantar i preparar-nos per a la Pasqua del 2021. <\/p>\n","protected":false},"featured_media":112,"template":"","class_list":["post-111","noticia","type-noticia","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.culturalvila-seca.cat\/caramelles\/wp-json\/wp\/v2\/noticia\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culturalvila-seca.cat\/caramelles\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.culturalvila-seca.cat\/caramelles\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.culturalvila-seca.cat\/caramelles\/wp-json\/wp\/v2\/media\/112"}],"wp:attachment":[{"href":"https:\/\/www.culturalvila-seca.cat\/caramelles\/wp-json\/wp\/v2\/media?parent=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}