{"id":80,"date":"2021-02-15T13:05:22","date_gmt":"2021-02-15T11:05:22","guid":{"rendered":"https:\/\/www.culturalvila-seca.cat\/cobladelcomu\/?post_type=phort_post&#038;p=80"},"modified":"2021-02-15T13:05:23","modified_gmt":"2021-02-15T11:05:23","slug":"seguici-sant-antoni","status":"publish","type":"phort_post","link":"https:\/\/www.culturalvila-seca.cat\/cobladelcomu\/album\/seguici-sant-antoni\/","title":{"rendered":"Seguici Sant Antoni"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":49,"template":"","meta":{"_acf_changed":false},"class_list":["post-80","phort_post","type-phort_post","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.culturalvila-seca.cat\/cobladelcomu\/wp-json\/wp\/v2\/phort_post\/80","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.culturalvila-seca.cat\/cobladelcomu\/wp-json\/wp\/v2\/phort_post"}],"about":[{"href":"https:\/\/www.culturalvila-seca.cat\/cobladelcomu\/wp-json\/wp\/v2\/types\/phort_post"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.culturalvila-seca.cat\/cobladelcomu\/wp-json\/wp\/v2\/media\/49"}],"wp:attachment":[{"href":"https:\/\/www.culturalvila-seca.cat\/cobladelcomu\/wp-json\/wp\/v2\/media?parent=80"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}